{"id":336,"count":1,"description":"","link":"https:\/\/lifehacksmag.com\/garden\/tag\/when-do-lilies-bloom\/","name":"when do lilies bloom","slug":"when-do-lilies-bloom","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/lifehacksmag.com\/garden\/wp-json\/wp\/v2\/tags\/336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifehacksmag.com\/garden\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/lifehacksmag.com\/garden\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/lifehacksmag.com\/garden\/wp-json\/wp\/v2\/posts?tags=336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}