{"id":1419,"count":1,"description":"","link":"https:\/\/lifehacksmag.com\/garden\/tag\/how-to-grow-pomegranates-from-seed\/","name":"how to grow pomegranates from seed","slug":"how-to-grow-pomegranates-from-seed","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/lifehacksmag.com\/garden\/wp-json\/wp\/v2\/tags\/1419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifehacksmag.com\/garden\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/lifehacksmag.com\/garden\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/lifehacksmag.com\/garden\/wp-json\/wp\/v2\/posts?tags=1419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}